{"id":29756,"date":"2018-10-17T09:27:49","date_gmt":"2018-10-17T08:27:49","guid":{"rendered":"https:\/\/www.aie.es\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/"},"modified":"2018-10-17T09:27:49","modified_gmt":"2018-10-17T08:27:49","slug":"las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos","status":"publish","type":"post","link":"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/","title":{"rendered":"Las salas de fiestas de Navarra piden que los menores puedan acceder a conciertos"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-26611\" src=\"https:\/\/www.aie.es\/wp-content\/uploads\/salasnavarra.jpg\" alt=\"\" width=\"940\" height=\"529\" srcset=\"https:\/\/www.aie.es\/wp-content\/uploads\/salasnavarra.jpg 940w, https:\/\/www.aie.es\/wp-content\/uploads\/salasnavarra-300x169.jpg 300w, https:\/\/www.aie.es\/wp-content\/uploads\/salasnavarra-768x432.jpg 768w, https:\/\/www.aie.es\/wp-content\/uploads\/salasnavarra-700x394.jpg 700w, https:\/\/www.aie.es\/wp-content\/uploads\/salasnavarra-539x303.jpg 539w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/p>\n<p>As\u00ed lo ha indicado el presidente de Kultura Live, Arkaitz Villar, en una sesi\u00f3n de trabajo parlamentaria, donde ha comparecido junto a otros representantes y a petici\u00f3n de los grupos que conforman el cuatripartito para informar sobre esta cuesti\u00f3n,\u00a0<a href=\"https:\/\/navarra.elespanol.com\/articulo\/sociedad\/espectaculos-musica-menores-pulsera-comision\/20181016171630225887.html\" target=\"_blank\" rel=\"noopener noreferrer\">informa el medio digital Navarra.com<\/a>,<\/p>\n<p><strong>\u201cEl acceso a la cultura es un derecho global, tambi\u00e9n de los menores\u201d<\/strong>, ha reivindicado Villar, que ha considerado de \u201cvital importancia\u201d avanzar legislativamente para que \u201clos menores de Navarra puedan acceder a salas de conciertos\u201d.<\/p>\n<p>De esta forma, ha pedido que los menores de 16 a\u00f1os puedan acceder a las salas de conciertos\u00a0<strong>mientras dure el espect\u00e1culo musical<\/strong>, siempre y cuando est\u00e9n acompa\u00f1ados por sus respectivos tutores legales, padres o madres. Seg\u00fan ha subrayado, los j\u00f3venes, que estar\u00e1n debidamente identificados, deber\u00e1n abandonar el local una vez finalizado el evento.<\/p>\n<p>\u201cPedimos que mientras est\u00e9n en estos espacios viendo el concierto, est\u00e9n de alguna manera identificados, con una\u00a0<strong>pulsera<\/strong>\u00a0o de otra forma\u201d, ha a\u00f1adido. Todos los grupos presentes han apoyado la iniciativa y se han mostrado dispuestos a estudiar la cuesti\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La asociaci\u00f3n de salas privadas de m\u00fasica en directo Kultura Live ha pedido una modificaci\u00f3n legislativa que permita que los menores de 16 a\u00f1os puedan acudir a espect\u00e1culos de m\u00fasica en vivo, siempre y cuando est\u00e9n debidamente acompa\u00f1ados e identificados y abandonen el local una vez finalizado el evento. <\/p>\n","protected":false},"author":3,"featured_media":26612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[323],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.9.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las salas de fiestas de Navarra piden que los menores puedan acceder a conciertos - AIE Sociedad de Artistas Int\u00e9rpretes o Ejecutantes de Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las salas de fiestas de Navarra piden que los menores puedan acceder a conciertos\" \/>\n<meta property=\"og:description\" content=\"La asociaci\u00f3n de salas privadas de m\u00fasica en directo Kultura Live ha pedido una modificaci\u00f3n legislativa que permita que los menores de 16 a\u00f1os puedan acudir a espect\u00e1culos de m\u00fasica en vivo, siempre y cuando est\u00e9n debidamente acompa\u00f1ados e identificados y abandonen el local una vez finalizado el evento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/\" \/>\n<meta property=\"og:site_name\" content=\"AIE Sociedad de Artistas Int\u00e9rpretes o Ejecutantes de Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-17T08:27:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aie.es\/wp-content\/uploads\/salasnavarra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"529\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GGCOM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GGCOM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/\",\"url\":\"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/\",\"name\":\"Las salas de fiestas de Navarra piden que los menores puedan acceder a conciertos - AIE Sociedad de Artistas Int\u00e9rpretes o Ejecutantes de Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\/\/www.aie.es\/#website\"},\"datePublished\":\"2018-10-17T08:27:49+00:00\",\"dateModified\":\"2018-10-17T08:27:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.aie.es\/#\/schema\/person\/9008ac87bc3b5836f79e2a677dace4d5\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.aie.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las salas de fiestas de Navarra piden que los menores puedan acceder a conciertos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aie.es\/#website\",\"url\":\"https:\/\/www.aie.es\/\",\"name\":\"AIE Sociedad de Artistas Int\u00e9rpretes o Ejecutantes de Espa\u00f1a\",\"description\":\"Entidad de gesti\u00f3n de derechos de propiedad intelectual\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.aie.es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.aie.es\/#\/schema\/person\/9008ac87bc3b5836f79e2a677dace4d5\",\"name\":\"GGCOM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.aie.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b4ed17baa0f661a7cbe0494fbec9b888?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b4ed17baa0f661a7cbe0494fbec9b888?s=96&d=mm&r=g\",\"caption\":\"GGCOM\"},\"url\":\"https:\/\/www.aie.es\/en\/author\/cgarriga\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las salas de fiestas de Navarra piden que los menores puedan acceder a conciertos - AIE Sociedad de Artistas Int\u00e9rpretes o Ejecutantes de Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/","og_locale":"en_US","og_type":"article","og_title":"Las salas de fiestas de Navarra piden que los menores puedan acceder a conciertos","og_description":"La asociaci\u00f3n de salas privadas de m\u00fasica en directo Kultura Live ha pedido una modificaci\u00f3n legislativa que permita que los menores de 16 a\u00f1os puedan acudir a espect\u00e1culos de m\u00fasica en vivo, siempre y cuando est\u00e9n debidamente acompa\u00f1ados e identificados y abandonen el local una vez finalizado el evento.","og_url":"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/","og_site_name":"AIE Sociedad de Artistas Int\u00e9rpretes o Ejecutantes de Espa\u00f1a","article_published_time":"2018-10-17T08:27:49+00:00","og_image":[{"width":940,"height":529,"url":"https:\/\/www.aie.es\/wp-content\/uploads\/salasnavarra.jpg","type":"image\/jpeg"}],"author":"GGCOM","twitter_card":"summary_large_image","twitter_misc":{"Written by":"GGCOM","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/","url":"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/","name":"Las salas de fiestas de Navarra piden que los menores puedan acceder a conciertos - AIE Sociedad de Artistas Int\u00e9rpretes o Ejecutantes de Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.aie.es\/#website"},"datePublished":"2018-10-17T08:27:49+00:00","dateModified":"2018-10-17T08:27:49+00:00","author":{"@id":"https:\/\/www.aie.es\/#\/schema\/person\/9008ac87bc3b5836f79e2a677dace4d5"},"breadcrumb":{"@id":"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aie.es\/en\/las-salas-de-fiestas-de-navarra-piden-que-los-menores-puedan-acceder-a-conciertos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aie.es\/en\/"},{"@type":"ListItem","position":2,"name":"Las salas de fiestas de Navarra piden que los menores puedan acceder a conciertos"}]},{"@type":"WebSite","@id":"https:\/\/www.aie.es\/#website","url":"https:\/\/www.aie.es\/","name":"AIE Sociedad de Artistas Int\u00e9rpretes o Ejecutantes de Espa\u00f1a","description":"Entidad de gesti\u00f3n de derechos de propiedad intelectual","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aie.es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.aie.es\/#\/schema\/person\/9008ac87bc3b5836f79e2a677dace4d5","name":"GGCOM","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aie.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b4ed17baa0f661a7cbe0494fbec9b888?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4ed17baa0f661a7cbe0494fbec9b888?s=96&d=mm&r=g","caption":"GGCOM"},"url":"https:\/\/www.aie.es\/en\/author\/cgarriga\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aie.es\/en\/wp-json\/wp\/v2\/posts\/29756"}],"collection":[{"href":"https:\/\/www.aie.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aie.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aie.es\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aie.es\/en\/wp-json\/wp\/v2\/comments?post=29756"}],"version-history":[{"count":0,"href":"https:\/\/www.aie.es\/en\/wp-json\/wp\/v2\/posts\/29756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aie.es\/en\/wp-json\/wp\/v2\/media\/26612"}],"wp:attachment":[{"href":"https:\/\/www.aie.es\/en\/wp-json\/wp\/v2\/media?parent=29756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aie.es\/en\/wp-json\/wp\/v2\/categories?post=29756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aie.es\/en\/wp-json\/wp\/v2\/tags?post=29756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}